{"id":3274,"date":"2020-02-04T15:06:25","date_gmt":"2020-02-04T20:06:25","guid":{"rendered":"http:\/\/wipware.com\/?p=3274"},"modified":"2022-01-21T10:54:59","modified_gmt":"2022-01-21T15:54:59","slug":"momentum-5-system-commission-at-pena-colorada","status":"publish","type":"post","link":"https:\/\/wipware.com\/it\/momentum-5-system-commission-at-pena-colorada\/","title":{"rendered":"Momentum 5 System Commission a Pena Colorada"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Il nostro tecnico WipWare, Thomas de Sousa, si \u00e8 recato a\u00a0<a href=\"http:\/\/www.pcolorada.com\/\">Pena Colorada<\/a>\u00a0in Messico dal 20 al 24 gennaio. Il viaggio consisteva nell&#039;ispezione dell&#039;installazione e della messa in servizio di un sistema di analisi della dimensione delle particelle Momentum 5 a 2 telecamere. Dopo aver goduto di una pausa dal nostro inverno in Ontario, ha incontrato il team metallurgico di Pena Colorada. Tommy ha ricevuto un caloroso benvenuto dal team di Pena Colorada. Tutti erano pronti per mettersi al lavoro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-previous-installation-inspection\">Ispezione dell&#039;installazione precedente<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un vantaggio per <a href=\"https:\/\/wipware.com\/it\/reliable-systems-means-repeat-customers-at-iamgold\/\">visitando i clienti esistenti<\/a><strong> <\/strong>\u00e8 l&#039;opportunit\u00e0 di rivedere i sistemi installati in precedenza. A volte, durante queste visite, i nostri clienti possono informare i nostri specialisti di eventuali problemi che hanno riscontrato. Con queste informazioni, i nostri specialisti tecnici possono indagare sul problema mentre si trovano in loco e aiutare a determinare cosa sta succedendo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se un sistema non funziona correttamente, il nostro team si prender\u00e0 del tempo per ispezionare e riparare in loco, se possibile. Quindi, quando Tommy \u00e8 arrivato sul posto, le installazioni di Momentum erano ancora in corso. Tommy ha utilizzato questo tempo per indagare sul problema del software e della connessione che si stava verificando con il precedente installato<strong> <\/strong><a href=\"https:\/\/wipware.com\/it\/products\/solo-conveyor-analysis-system\/\">Sistema Solo 5<\/a>. Il team ha deciso che Tommy sarebbe tornato a casa con la testa della telecamera per risolvere eventuali problemi con la telecamera. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-new-momentum-5-commissioning\">Nuova messa in servizio di Momentum 5<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dopo aver completato l&#039;ispezione del sistema Solo 5, Tommy ha proceduto alla messa in servizio del sistema Momentum 5 a 2 telecamere. Il primo passo per la messa in servizio di questo sistema \u00e8 stato l&#039;ispezione delle due installazioni preliminari. <\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"634\" height=\"476\" src=\"https:\/\/wipware.com\/wp-content\/uploads\/2021\/03\/Momentum-5-Pic-1.png\" alt=\"\" class=\"wp-image-5262 size-full\" srcset=\"https:\/\/wipware.com\/wp-content\/uploads\/2021\/03\/Momentum-5-Pic-1.png 634w, https:\/\/wipware.com\/wp-content\/uploads\/2021\/03\/Momentum-5-Pic-1-300x225.png 300w\" sizes=\"auto, (max-width: 634px) 100vw, 634px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Dopo l&#039;ispezione iniziale, hanno eretto i telai Momentum. Tutti i cavi elettrici e di rete sono stati controllati e l&#039;installazione \u00e8 stata buona. Il nostro specialista tecnico apprezza sempre il lavoro preliminare che i nostri clienti fanno prima del loro arrivo.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"411\" height=\"309\" src=\"https:\/\/wipware.com\/wp-content\/uploads\/2021\/03\/Momentum-5-Pic-2.png\" alt=\"\" class=\"wp-image-5263 size-full\" srcset=\"https:\/\/wipware.com\/wp-content\/uploads\/2021\/03\/Momentum-5-Pic-2.png 411w, https:\/\/wipware.com\/wp-content\/uploads\/2021\/03\/Momentum-5-Pic-2-300x226.png 300w\" sizes=\"auto, (max-width: 411px) 100vw, 411px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Il terzo passaggio consisteva nell&#039;aggiungere il gruppo telecamera a ciascun fotogramma e calibrare il sistema. L&#039;installazione e le calibrazioni sono state completate con successo ed era ora di chiamarlo un giorno.<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Il giorno successivo, dopo la messa in servizio del sistema, il nostro specialista tecnico ha fornito formazione alla squadra prima di partire e tornare in Canada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il sistema Momentum 5 sta ora raccogliendo la telemetria della dimensione delle particelle in tempo reale su due nastri trasportatori.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cEfficienza e produttivit\u00e0 per il nostro processo di arricchimento: la tecnologia WipFrag Momentum 5 System\u00ae di WipWare Inc. ci consente di misurare, monitorare e controllare, in tempo reale, la distribuzione di dimensioni, forma, uniformit\u00e0 e volume del minerale di ferro che alimenta il mulino autogeno . Conoscere l&#039;entit\u00e0 dell&#039;impatto delle diverse frazioni di minerale alimentato, migliora le prestazioni della macinazione autogena dal martello, aumentando l&#039;efficienza energetica nei mulini e la produttivit\u00e0 del processo di arricchimento. \u2013 Da Pena Colorada<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Grazie al <a href=\"https:\/\/wipware.com\/it\/pena-colorada-mexico-commissioning-of-solo-system\/\">La squadra di Pena Colorada<\/a><strong> <\/strong>per tutta la loro assistenza.<\/p>","protected":false},"excerpt":{"rendered":"<p>Lo specialista tecnico di WipWare si \u00e8 recato a Pena Colorada in Messico per commissionare il sistema di analisi della dimensione delle particelle Momentum 5.<\/p>","protected":false},"author":6,"featured_media":5264,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[38],"tags":[],"class_list":["post-3274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-installations"],"acf":{"related_posts":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Momentum 5 System Commission at Pena Colorada &#8226; WipWare<\/title>\n<meta name=\"description\" content=\"WipWare&#039;s Technical Specialist travelled to Pena Colorada in Mexico to commission our Momentum 5 Particle Size Analysis System.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wipware.com\/it\/momentum-5-system-commission-at-pena-colorada\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Momentum 5 System Commission at Pena Colorada\" \/>\n<meta property=\"og:description\" content=\"WipWare - Because you can&#039;t manage what you can&#039;t measure. Fragmentation analysis from Mine to Mill\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wipware.com\/it\/momentum-5-system-commission-at-pena-colorada\/\" \/>\n<meta property=\"og:site_name\" content=\"WipWare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WipWare\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-04T20:06:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-21T15:54:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wipware.com\/wp-content\/uploads\/2020\/02\/pena.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1008\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kim Coyle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WipWare\" \/>\n<meta name=\"twitter:site\" content=\"@WipWare\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kim Coyle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wipware.com\\\/momentum-5-system-commission-at-pena-colorada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/momentum-5-system-commission-at-pena-colorada\\\/\"},\"author\":{\"name\":\"Kim Coyle\",\"@id\":\"https:\\\/\\\/wipware.com\\\/it\\\/#\\\/schema\\\/person\\\/44f82b527b7df4ccce9afb09c1f1c375\"},\"headline\":\"Momentum 5 System Commission at Pena Colorada\",\"datePublished\":\"2020-02-04T20:06:25+00:00\",\"dateModified\":\"2022-01-21T15:54:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/momentum-5-system-commission-at-pena-colorada\\\/\"},\"wordCount\":425,\"publisher\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/momentum-5-system-commission-at-pena-colorada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wipware.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/pena.jpg\",\"articleSection\":[\"Installations\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wipware.com\\\/momentum-5-system-commission-at-pena-colorada\\\/\",\"url\":\"https:\\\/\\\/wipware.com\\\/momentum-5-system-commission-at-pena-colorada\\\/\",\"name\":\"Momentum 5 System Commission at Pena Colorada &#8226; WipWare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/momentum-5-system-commission-at-pena-colorada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/momentum-5-system-commission-at-pena-colorada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wipware.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/pena.jpg\",\"datePublished\":\"2020-02-04T20:06:25+00:00\",\"dateModified\":\"2022-01-21T15:54:59+00:00\",\"description\":\"WipWare's Technical Specialist travelled to Pena Colorada in Mexico to commission our Momentum 5 Particle Size Analysis System.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/momentum-5-system-commission-at-pena-colorada\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wipware.com\\\/momentum-5-system-commission-at-pena-colorada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/wipware.com\\\/momentum-5-system-commission-at-pena-colorada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wipware.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/pena.jpg\",\"contentUrl\":\"https:\\\/\\\/wipware.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/pena.jpg\",\"width\":1008,\"height\":520,\"caption\":\"Pena\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wipware.com\\\/momentum-5-system-commission-at-pena-colorada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wipware.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Momentum 5 System Commission at Pena Colorada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wipware.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/wipware.com\\\/it\\\/\",\"name\":\"WipWare Inc\",\"description\":\"Real-Time Fragmentation Analysis Systems &amp; Software\",\"publisher\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/it\\\/#organization\"},\"alternateName\":\"WipWare\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wipware.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wipware.com\\\/it\\\/#organization\",\"name\":\"WipWare Inc\",\"alternateName\":\"WipWare\",\"url\":\"https:\\\/\\\/wipware.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/wipware.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wipware.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/W-Social-Icon.jpg\",\"contentUrl\":\"https:\\\/\\\/wipware.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/W-Social-Icon.jpg\",\"width\":400,\"height\":400,\"caption\":\"WipWare Inc\"},\"image\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WipWare\\\/\",\"https:\\\/\\\/x.com\\\/WipWare\",\"https:\\\/\\\/www.instagram.com\\\/wipware\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/wipware-inc-\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Wipware\"],\"publishingPrinciples\":\"https:\\\/\\\/wipware.com\\\/fr\\\/newsfeed\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/wipware.com\\\/about-us\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/wipware.com\\\/privacy-policy\\\/\",\"correctionsPolicy\":\"https:\\\/\\\/wipware.com\\\/terms-and-conditions\\\/\",\"ethicsPolicy\":\"https:\\\/\\\/wipware.com\\\/about-us\\\/\",\"diversityPolicy\":\"https:\\\/\\\/wipware.com\\\/about-us\\\/\",\"diversityStaffingReport\":\"https:\\\/\\\/wipware.com\\\/about-us\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wipware.com\\\/it\\\/#\\\/schema\\\/person\\\/44f82b527b7df4ccce9afb09c1f1c375\",\"name\":\"Kim Coyle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5dce10b9fd06f52ce046161568a2bf9802a102cbfbe74d1ca5ac2312482d633?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5dce10b9fd06f52ce046161568a2bf9802a102cbfbe74d1ca5ac2312482d633?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5dce10b9fd06f52ce046161568a2bf9802a102cbfbe74d1ca5ac2312482d633?s=96&d=mm&r=g\",\"caption\":\"Kim Coyle\"},\"url\":\"https:\\\/\\\/wipware.com\\\/it\\\/author\\\/kimcoyle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Momentum 5 System Commission at Pena Colorada &#8226; WipWare","description":"Lo specialista tecnico di WipWare si \u00e8 recato a Pena Colorada in Messico per commissionare il nostro sistema di analisi della dimensione delle particelle Momentum 5.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wipware.com\/it\/momentum-5-system-commission-at-pena-colorada\/","og_locale":"it_IT","og_type":"article","og_title":"Momentum 5 System Commission at Pena Colorada","og_description":"WipWare - Because you can't manage what you can't measure. Fragmentation analysis from Mine to Mill","og_url":"https:\/\/wipware.com\/it\/momentum-5-system-commission-at-pena-colorada\/","og_site_name":"WipWare","article_publisher":"https:\/\/www.facebook.com\/WipWare\/","article_published_time":"2020-02-04T20:06:25+00:00","article_modified_time":"2022-01-21T15:54:59+00:00","og_image":[{"width":1008,"height":520,"url":"https:\/\/wipware.com\/wp-content\/uploads\/2020\/02\/pena.jpg","type":"image\/jpeg"}],"author":"Kim Coyle","twitter_card":"summary_large_image","twitter_creator":"@WipWare","twitter_site":"@WipWare","twitter_misc":{"Scritto da":"Kim Coyle","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wipware.com\/momentum-5-system-commission-at-pena-colorada\/#article","isPartOf":{"@id":"https:\/\/wipware.com\/momentum-5-system-commission-at-pena-colorada\/"},"author":{"name":"Kim Coyle","@id":"https:\/\/wipware.com\/it\/#\/schema\/person\/44f82b527b7df4ccce9afb09c1f1c375"},"headline":"Momentum 5 System Commission at Pena Colorada","datePublished":"2020-02-04T20:06:25+00:00","dateModified":"2022-01-21T15:54:59+00:00","mainEntityOfPage":{"@id":"https:\/\/wipware.com\/momentum-5-system-commission-at-pena-colorada\/"},"wordCount":425,"publisher":{"@id":"https:\/\/wipware.com\/it\/#organization"},"image":{"@id":"https:\/\/wipware.com\/momentum-5-system-commission-at-pena-colorada\/#primaryimage"},"thumbnailUrl":"https:\/\/wipware.com\/wp-content\/uploads\/2020\/02\/pena.jpg","articleSection":["Installations"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/wipware.com\/momentum-5-system-commission-at-pena-colorada\/","url":"https:\/\/wipware.com\/momentum-5-system-commission-at-pena-colorada\/","name":"Momentum 5 System Commission at Pena Colorada &#8226; WipWare","isPartOf":{"@id":"https:\/\/wipware.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wipware.com\/momentum-5-system-commission-at-pena-colorada\/#primaryimage"},"image":{"@id":"https:\/\/wipware.com\/momentum-5-system-commission-at-pena-colorada\/#primaryimage"},"thumbnailUrl":"https:\/\/wipware.com\/wp-content\/uploads\/2020\/02\/pena.jpg","datePublished":"2020-02-04T20:06:25+00:00","dateModified":"2022-01-21T15:54:59+00:00","description":"Lo specialista tecnico di WipWare si \u00e8 recato a Pena Colorada in Messico per commissionare il nostro sistema di analisi della dimensione delle particelle Momentum 5.","breadcrumb":{"@id":"https:\/\/wipware.com\/momentum-5-system-commission-at-pena-colorada\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wipware.com\/momentum-5-system-commission-at-pena-colorada\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/wipware.com\/momentum-5-system-commission-at-pena-colorada\/#primaryimage","url":"https:\/\/wipware.com\/wp-content\/uploads\/2020\/02\/pena.jpg","contentUrl":"https:\/\/wipware.com\/wp-content\/uploads\/2020\/02\/pena.jpg","width":1008,"height":520,"caption":"Pena"},{"@type":"BreadcrumbList","@id":"https:\/\/wipware.com\/momentum-5-system-commission-at-pena-colorada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wipware.com\/"},{"@type":"ListItem","position":2,"name":"Momentum 5 System Commission at Pena Colorada"}]},{"@type":"WebSite","@id":"https:\/\/wipware.com\/it\/#website","url":"https:\/\/wipware.com\/it\/","name":"WipWare Inc","description":"Sistemi e software di analisi della frammentazione in tempo reale","publisher":{"@id":"https:\/\/wipware.com\/it\/#organization"},"alternateName":"WipWare","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wipware.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/wipware.com\/it\/#organization","name":"WipWare Inc","alternateName":"WipWare","url":"https:\/\/wipware.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/wipware.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/wipware.com\/wp-content\/uploads\/2023\/09\/W-Social-Icon.jpg","contentUrl":"https:\/\/wipware.com\/wp-content\/uploads\/2023\/09\/W-Social-Icon.jpg","width":400,"height":400,"caption":"WipWare Inc"},"image":{"@id":"https:\/\/wipware.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WipWare\/","https:\/\/x.com\/WipWare","https:\/\/www.instagram.com\/wipware\/","https:\/\/www.linkedin.com\/company\/wipware-inc-\/","https:\/\/www.youtube.com\/user\/Wipware"],"publishingPrinciples":"https:\/\/wipware.com\/fr\/newsfeed\/","ownershipFundingInfo":"https:\/\/wipware.com\/about-us\/","actionableFeedbackPolicy":"https:\/\/wipware.com\/privacy-policy\/","correctionsPolicy":"https:\/\/wipware.com\/terms-and-conditions\/","ethicsPolicy":"https:\/\/wipware.com\/about-us\/","diversityPolicy":"https:\/\/wipware.com\/about-us\/","diversityStaffingReport":"https:\/\/wipware.com\/about-us\/"},{"@type":"Person","@id":"https:\/\/wipware.com\/it\/#\/schema\/person\/44f82b527b7df4ccce9afb09c1f1c375","name":"Kim Coyle","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f5dce10b9fd06f52ce046161568a2bf9802a102cbfbe74d1ca5ac2312482d633?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f5dce10b9fd06f52ce046161568a2bf9802a102cbfbe74d1ca5ac2312482d633?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f5dce10b9fd06f52ce046161568a2bf9802a102cbfbe74d1ca5ac2312482d633?s=96&d=mm&r=g","caption":"Kim Coyle"},"url":"https:\/\/wipware.com\/it\/author\/kimcoyle\/"}]}},"_links":{"self":[{"href":"https:\/\/wipware.com\/it\/wp-json\/wp\/v2\/posts\/3274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wipware.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wipware.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wipware.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/wipware.com\/it\/wp-json\/wp\/v2\/comments?post=3274"}],"version-history":[{"count":7,"href":"https:\/\/wipware.com\/it\/wp-json\/wp\/v2\/posts\/3274\/revisions"}],"predecessor-version":[{"id":6520,"href":"https:\/\/wipware.com\/it\/wp-json\/wp\/v2\/posts\/3274\/revisions\/6520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wipware.com\/it\/wp-json\/wp\/v2\/media\/5264"}],"wp:attachment":[{"href":"https:\/\/wipware.com\/it\/wp-json\/wp\/v2\/media?parent=3274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wipware.com\/it\/wp-json\/wp\/v2\/categories?post=3274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wipware.com\/it\/wp-json\/wp\/v2\/tags?post=3274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}