{"id":1304,"date":"2018-01-08T12:49:44","date_gmt":"2018-01-08T17:49:44","guid":{"rendered":"http:\/\/wipware.com\/?p=1304"},"modified":"2025-11-14T12:06:42","modified_gmt":"2025-11-14T17:06:42","slug":"wipware-signs-agreement-with-haver-boecker","status":"publish","type":"post","link":"https:\/\/wipware.com\/de\/wipware-signs-agreement-with-haver-boecker\/","title":{"rendered":"WipWare unterzeichnet Vertrag mit Haver &amp; Boecker"},"content":{"rendered":"<p>WipWare freut sich, Ihnen mitteilen zu k\u00f6nnen, dass wir mit der Haver &amp; Boecker OHG in Oelde, Deutschland, einen Vertrag \u00fcber den Umgang mit unseren Produkten unterzeichnet haben. Haver &amp; Boecker ist ein f\u00fchrender Hersteller von Verarbeitungs-, Lager-, Mischverpackungs-, Abf\u00fcll-, Palettier- und Verladesystemen. Die Mission des Unternehmens ist es, das Beste dieser Technologien auf den Markt zu bringen.<br \/>\nSiehe ihre Website hier:<a href=\"http:\/\/www.havercanada.com\/\"> Haver &amp; Boecker Kanada<\/a><\/p>\n<p>\u201eWS Tyler, einer ihrer Gesch\u00e4ftsbereiche, ist bekannt f\u00fcr seine Standards bei Bildschirmmedien, und es ist eine komplement\u00e4re und nat\u00fcrliche Erg\u00e4nzung, bei der Charakterisierung von Materialien zusammenzuarbeiten\u201c, sagt Tom Palangio, Pr\u00e4sident von WipWare.<\/p>\n<p>Das 1887 von Carl Haver und Eduard Boecker gegr\u00fcndete Unternehmen produziert seit jeher Produkte f\u00fcr Steinbr\u00fcche, Sand und Kies, D\u00fcngemittel, Farben, Pulverbeschichtungen, Chemie- und Pharmaunternehmen sowie die Lebensmittelindustrie \u2013 Analyseger\u00e4te von Haver &amp; Boecker werden in fast allen Bereichen der Industrie.<\/p>","protected":false},"excerpt":{"rendered":"<p>WipWare is pleased to announce that we have signed an agreement with Haver &amp; Boecker OHG in Oelde, Germany to handle our products. Haver &amp; Boecker is a leading manufacturer in processing, storage, mixing packing, filling, palletizing and loading systems. The company&#8217;s mission is to deliver the best of these technologies to the marketplace. See [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":6583,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[72],"tags":[],"class_list":["post-1304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wipware"],"acf":{"related_posts":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>WipWare Signs Agreement with Haver &amp; Boecker &#8226; WipWare<\/title>\n<meta name=\"description\" content=\"WipWare has signed a partner agreement with Haver &amp; Boecker Germany. We are excited to be able to expand our business and products.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wipware.com\/de\/wipware-signs-agreement-with-haver-boecker\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WipWare Signs Agreement with Haver &amp; Boecker\" \/>\n<meta property=\"og:description\" content=\"WipWare - Because you can&#039;t manage what you can&#039;t measure. Fragmentation analysis from Mine to Mill\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wipware.com\/de\/wipware-signs-agreement-with-haver-boecker\/\" \/>\n<meta property=\"og:site_name\" content=\"WipWare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WipWare\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-08T17:49:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-14T17:06:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wipware.com\/wp-content\/uploads\/2021\/04\/Pit-to-Plant-Image-e1619706651355.png\" \/>\n\t<meta property=\"og:image:width\" content=\"916\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Kim Coyle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WipWare\" \/>\n<meta name=\"twitter:site\" content=\"@WipWare\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kim Coyle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wipware.com\\\/wipware-signs-agreement-with-haver-boecker\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/wipware-signs-agreement-with-haver-boecker\\\/\"},\"author\":{\"name\":\"Kim Coyle\",\"@id\":\"https:\\\/\\\/wipware.com\\\/it\\\/#\\\/schema\\\/person\\\/44f82b527b7df4ccce9afb09c1f1c375\"},\"headline\":\"WipWare Signs Agreement with Haver &#038; Boecker\",\"datePublished\":\"2018-01-08T17:49:44+00:00\",\"dateModified\":\"2025-11-14T17:06:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/wipware-signs-agreement-with-haver-boecker\\\/\"},\"wordCount\":150,\"publisher\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/wipware-signs-agreement-with-haver-boecker\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wipware.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Haver_Boecker.svg\",\"articleSection\":[\"WipWare\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wipware.com\\\/wipware-signs-agreement-with-haver-boecker\\\/\",\"url\":\"https:\\\/\\\/wipware.com\\\/wipware-signs-agreement-with-haver-boecker\\\/\",\"name\":\"WipWare Signs Agreement with Haver & Boecker &#8226; WipWare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/wipware-signs-agreement-with-haver-boecker\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/wipware-signs-agreement-with-haver-boecker\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wipware.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Haver_Boecker.svg\",\"datePublished\":\"2018-01-08T17:49:44+00:00\",\"dateModified\":\"2025-11-14T17:06:42+00:00\",\"description\":\"WipWare has signed a partner agreement with Haver & Boecker Germany. We are excited to be able to expand our business and products.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/wipware-signs-agreement-with-haver-boecker\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wipware.com\\\/wipware-signs-agreement-with-haver-boecker\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wipware.com\\\/wipware-signs-agreement-with-haver-boecker\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wipware.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Haver_Boecker.svg\",\"contentUrl\":\"https:\\\/\\\/wipware.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Haver_Boecker.svg\",\"width\":383,\"height\":249},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wipware.com\\\/wipware-signs-agreement-with-haver-boecker\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wipware.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WipWare Signs Agreement with Haver &#038; Boecker\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wipware.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/wipware.com\\\/it\\\/\",\"name\":\"WipWare Inc\",\"description\":\"Real-Time Fragmentation Analysis Systems &amp; Software\",\"publisher\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/it\\\/#organization\"},\"alternateName\":\"WipWare\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wipware.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wipware.com\\\/it\\\/#organization\",\"name\":\"WipWare Inc\",\"alternateName\":\"WipWare\",\"url\":\"https:\\\/\\\/wipware.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wipware.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wipware.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/W-Social-Icon.jpg\",\"contentUrl\":\"https:\\\/\\\/wipware.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/W-Social-Icon.jpg\",\"width\":400,\"height\":400,\"caption\":\"WipWare Inc\"},\"image\":{\"@id\":\"https:\\\/\\\/wipware.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WipWare\\\/\",\"https:\\\/\\\/x.com\\\/WipWare\",\"https:\\\/\\\/www.instagram.com\\\/wipware\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/wipware-inc-\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Wipware\"],\"publishingPrinciples\":\"https:\\\/\\\/wipware.com\\\/fr\\\/newsfeed\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/wipware.com\\\/about-us\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/wipware.com\\\/privacy-policy\\\/\",\"correctionsPolicy\":\"https:\\\/\\\/wipware.com\\\/terms-and-conditions\\\/\",\"ethicsPolicy\":\"https:\\\/\\\/wipware.com\\\/about-us\\\/\",\"diversityPolicy\":\"https:\\\/\\\/wipware.com\\\/about-us\\\/\",\"diversityStaffingReport\":\"https:\\\/\\\/wipware.com\\\/about-us\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wipware.com\\\/it\\\/#\\\/schema\\\/person\\\/44f82b527b7df4ccce9afb09c1f1c375\",\"name\":\"Kim Coyle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5dce10b9fd06f52ce046161568a2bf9802a102cbfbe74d1ca5ac2312482d633?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5dce10b9fd06f52ce046161568a2bf9802a102cbfbe74d1ca5ac2312482d633?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5dce10b9fd06f52ce046161568a2bf9802a102cbfbe74d1ca5ac2312482d633?s=96&d=mm&r=g\",\"caption\":\"Kim Coyle\"},\"url\":\"https:\\\/\\\/wipware.com\\\/de\\\/author\\\/kimcoyle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"WipWare Signs Agreement with Haver & Boecker &#8226; WipWare","description":"WipWare hat einen Partnervertrag mit Haver &amp; Boecker Deutschland unterzeichnet. Wir freuen uns, unser Gesch\u00e4ft und unsere Produkte erweitern zu k\u00f6nnen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wipware.com\/de\/wipware-signs-agreement-with-haver-boecker\/","og_locale":"de_DE","og_type":"article","og_title":"WipWare Signs Agreement with Haver & Boecker","og_description":"WipWare - Because you can't manage what you can't measure. Fragmentation analysis from Mine to Mill","og_url":"https:\/\/wipware.com\/de\/wipware-signs-agreement-with-haver-boecker\/","og_site_name":"WipWare","article_publisher":"https:\/\/www.facebook.com\/WipWare\/","article_published_time":"2018-01-08T17:49:44+00:00","article_modified_time":"2025-11-14T17:06:42+00:00","og_image":[{"width":916,"height":514,"url":"https:\/\/wipware.com\/wp-content\/uploads\/2021\/04\/Pit-to-Plant-Image-e1619706651355.png","type":"image\/png"}],"author":"Kim Coyle","twitter_card":"summary_large_image","twitter_creator":"@WipWare","twitter_site":"@WipWare","twitter_misc":{"Verfasst von":"Kim Coyle","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wipware.com\/wipware-signs-agreement-with-haver-boecker\/#article","isPartOf":{"@id":"https:\/\/wipware.com\/wipware-signs-agreement-with-haver-boecker\/"},"author":{"name":"Kim Coyle","@id":"https:\/\/wipware.com\/it\/#\/schema\/person\/44f82b527b7df4ccce9afb09c1f1c375"},"headline":"WipWare Signs Agreement with Haver &#038; Boecker","datePublished":"2018-01-08T17:49:44+00:00","dateModified":"2025-11-14T17:06:42+00:00","mainEntityOfPage":{"@id":"https:\/\/wipware.com\/wipware-signs-agreement-with-haver-boecker\/"},"wordCount":150,"publisher":{"@id":"https:\/\/wipware.com\/it\/#organization"},"image":{"@id":"https:\/\/wipware.com\/wipware-signs-agreement-with-haver-boecker\/#primaryimage"},"thumbnailUrl":"https:\/\/wipware.com\/wp-content\/uploads\/2022\/04\/Haver_Boecker.svg","articleSection":["WipWare"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/wipware.com\/wipware-signs-agreement-with-haver-boecker\/","url":"https:\/\/wipware.com\/wipware-signs-agreement-with-haver-boecker\/","name":"WipWare Signs Agreement with Haver & Boecker &#8226; WipWare","isPartOf":{"@id":"https:\/\/wipware.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wipware.com\/wipware-signs-agreement-with-haver-boecker\/#primaryimage"},"image":{"@id":"https:\/\/wipware.com\/wipware-signs-agreement-with-haver-boecker\/#primaryimage"},"thumbnailUrl":"https:\/\/wipware.com\/wp-content\/uploads\/2022\/04\/Haver_Boecker.svg","datePublished":"2018-01-08T17:49:44+00:00","dateModified":"2025-11-14T17:06:42+00:00","description":"WipWare hat einen Partnervertrag mit Haver &amp; Boecker Deutschland unterzeichnet. Wir freuen uns, unser Gesch\u00e4ft und unsere Produkte erweitern zu k\u00f6nnen.","breadcrumb":{"@id":"https:\/\/wipware.com\/wipware-signs-agreement-with-haver-boecker\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wipware.com\/wipware-signs-agreement-with-haver-boecker\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wipware.com\/wipware-signs-agreement-with-haver-boecker\/#primaryimage","url":"https:\/\/wipware.com\/wp-content\/uploads\/2022\/04\/Haver_Boecker.svg","contentUrl":"https:\/\/wipware.com\/wp-content\/uploads\/2022\/04\/Haver_Boecker.svg","width":383,"height":249},{"@type":"BreadcrumbList","@id":"https:\/\/wipware.com\/wipware-signs-agreement-with-haver-boecker\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wipware.com\/"},{"@type":"ListItem","position":2,"name":"WipWare Signs Agreement with Haver &#038; Boecker"}]},{"@type":"WebSite","@id":"https:\/\/wipware.com\/it\/#website","url":"https:\/\/wipware.com\/it\/","name":"WipWare Inc","description":"Systeme und Software zur Echtzeit-Fragmentierungsanalyse","publisher":{"@id":"https:\/\/wipware.com\/it\/#organization"},"alternateName":"WipWare","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wipware.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wipware.com\/it\/#organization","name":"WipWare Inc","alternateName":"WipWare","url":"https:\/\/wipware.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wipware.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/wipware.com\/wp-content\/uploads\/2023\/09\/W-Social-Icon.jpg","contentUrl":"https:\/\/wipware.com\/wp-content\/uploads\/2023\/09\/W-Social-Icon.jpg","width":400,"height":400,"caption":"WipWare Inc"},"image":{"@id":"https:\/\/wipware.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WipWare\/","https:\/\/x.com\/WipWare","https:\/\/www.instagram.com\/wipware\/","https:\/\/www.linkedin.com\/company\/wipware-inc-\/","https:\/\/www.youtube.com\/user\/Wipware"],"publishingPrinciples":"https:\/\/wipware.com\/fr\/newsfeed\/","ownershipFundingInfo":"https:\/\/wipware.com\/about-us\/","actionableFeedbackPolicy":"https:\/\/wipware.com\/privacy-policy\/","correctionsPolicy":"https:\/\/wipware.com\/terms-and-conditions\/","ethicsPolicy":"https:\/\/wipware.com\/about-us\/","diversityPolicy":"https:\/\/wipware.com\/about-us\/","diversityStaffingReport":"https:\/\/wipware.com\/about-us\/"},{"@type":"Person","@id":"https:\/\/wipware.com\/it\/#\/schema\/person\/44f82b527b7df4ccce9afb09c1f1c375","name":"Kim Coyle","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f5dce10b9fd06f52ce046161568a2bf9802a102cbfbe74d1ca5ac2312482d633?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f5dce10b9fd06f52ce046161568a2bf9802a102cbfbe74d1ca5ac2312482d633?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f5dce10b9fd06f52ce046161568a2bf9802a102cbfbe74d1ca5ac2312482d633?s=96&d=mm&r=g","caption":"Kim Coyle"},"url":"https:\/\/wipware.com\/de\/author\/kimcoyle\/"}]}},"_links":{"self":[{"href":"https:\/\/wipware.com\/de\/wp-json\/wp\/v2\/posts\/1304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wipware.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wipware.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wipware.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/wipware.com\/de\/wp-json\/wp\/v2\/comments?post=1304"}],"version-history":[{"count":3,"href":"https:\/\/wipware.com\/de\/wp-json\/wp\/v2\/posts\/1304\/revisions"}],"predecessor-version":[{"id":6585,"href":"https:\/\/wipware.com\/de\/wp-json\/wp\/v2\/posts\/1304\/revisions\/6585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wipware.com\/de\/wp-json\/wp\/v2\/media\/6583"}],"wp:attachment":[{"href":"https:\/\/wipware.com\/de\/wp-json\/wp\/v2\/media?parent=1304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wipware.com\/de\/wp-json\/wp\/v2\/categories?post=1304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wipware.com\/de\/wp-json\/wp\/v2\/tags?post=1304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}